{"id":14083,"date":"2025-12-09T14:27:07","date_gmt":"2025-12-09T07:27:07","guid":{"rendered":"https:\/\/bcnu.ac.th\/bcnunews\/?p=14083"},"modified":"2025-12-09T14:27:07","modified_gmt":"2025-12-09T07:27:07","slug":"%e0%b8%87%e0%b8%9a%e0%b8%97%e0%b8%94%e0%b8%a5%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%94%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b8%9e%e0%b8%a4%e0%b8%a8%e0%b8%88%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a2%e0%b8%99-2568","status":"publish","type":"post","link":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/news\/trial-balance\/14083\/","title":{"rendered":"\u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568"},"content":{"rendered":"<p><a href=\"http:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/12\/2.-\u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19-2568.pdf\">2. \u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2. \u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568<\/p>\n","protected":false},"author":3,"featured_media":11777,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[],"class_list":["post-14083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trial-balance"],"_links":{"self":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/14083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/comments?post=14083"}],"version-history":[{"count":1,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/14083\/revisions"}],"predecessor-version":[{"id":14085,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/14083\/revisions\/14085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/media\/11777"}],"wp:attachment":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/media?parent=14083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/categories?post=14083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/tags?post=14083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}