{"id":13980,"date":"2025-10-09T10:30:40","date_gmt":"2025-10-09T03:30:40","guid":{"rendered":"https:\/\/bcnu.ac.th\/bcnunews\/?p=13980"},"modified":"2025-10-09T10:30:50","modified_gmt":"2025-10-09T03:30:50","slug":"%e0%b8%87%e0%b8%9a%e0%b8%97%e0%b8%94%e0%b8%a5%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b9%80%e0%b8%94%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2-2","status":"publish","type":"post","link":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/news\/trial-balance\/13980\/","title":{"rendered":"\u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568"},"content":{"rendered":"<p><a href=\"http:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/10\/\u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19-2568.pdf\">\u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e07\u0e1a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568<\/p>\n","protected":false},"author":3,"featured_media":11777,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[],"class_list":["post-13980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trial-balance"],"_links":{"self":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/13980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/comments?post=13980"}],"version-history":[{"count":1,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/13980\/revisions"}],"predecessor-version":[{"id":13982,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/13980\/revisions\/13982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/media\/11777"}],"wp:attachment":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/media?parent=13980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/categories?post=13980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/tags?post=13980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}