{"id":13920,"date":"2025-08-19T09:13:16","date_gmt":"2025-08-19T02:13:16","guid":{"rendered":"https:\/\/bcnu.ac.th\/bcnunews\/?p=13920"},"modified":"2025-09-04T09:14:05","modified_gmt":"2025-09-04T02:14:05","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b9%80%e0%b8%8a%e0%b8%b4%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/news\/activity\/13920\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 Manuscript Research Camp"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-13909\" src=\"http:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/09\/6-212x300.png\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/09\/6-212x300.png 212w, https:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/09\/6-724x1024.png 724w, https:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/09\/6-768x1086.png 768w, https:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/09\/6-1086x1536.png 1086w, https:\/\/bcnu.ac.th\/bcnunews\/wp-content\/uploads\/2025\/09\/6.png 1414w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":13909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[],"class_list":["post-13920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/13920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/comments?post=13920"}],"version-history":[{"count":1,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/13920\/revisions"}],"predecessor-version":[{"id":13921,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/posts\/13920\/revisions\/13921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/media\/13909"}],"wp:attachment":[{"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/media?parent=13920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/categories?post=13920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bcnu.ac.th\/bcnunews\/index.php\/wp-json\/wp\/v2\/tags?post=13920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}